{"id":1659,"date":"2014-05-21T11:10:21","date_gmt":"2014-05-21T09:10:21","guid":{"rendered":"http:\/\/www.laconsolata.org\/?page_id=1659"},"modified":"2026-01-28T16:44:43","modified_gmt":"2026-01-28T15:44:43","slug":"volumi-terzo-centenario","status":"publish","type":"page","link":"https:\/\/www.laconsolata.org\/index.php\/come-iscriversi\/volumi-terzo-centenario\/","title":{"rendered":"Volumi Terzo Centenario"},"content":{"rendered":"<p><a href=\"http:\/\/www.laconsolata.org\/wp-content\/uploads\/2014\/05\/300-copertina.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-1660\" alt=\"300-copertina\" src=\"http:\/\/www.laconsolata.org\/wp-content\/uploads\/2014\/05\/300-copertina.jpg\" width=\"520\" height=\"734\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00a0\u00a0 <\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Saggio sui 300 anni della Consolata Patrona di Torino<\/strong><\/p>\n<p>Il volume si propone di presentare, anzitutto, i\u00a0 momenti essenziali delle circostanze che portarono la Citt\u00e0 di Torino a deliberare la consacrazione della Citt\u00e0 alla Madre di Dio Consolatrice e Consolata (21 Maggio 1714), come segno perenne di ringraziamento dalla temuta distruzione nell\u2019assedio del 1706.<\/p>\n<p>Un altro obiettivo del volume \u00e8 quello di inserire le vicende millenarie del Santuario della Patrona di Torino all\u2019interno della vita militare, civile e religiosa di Torino ed, infine, offrire una guida religiosa, culturale, artistica su quel complesso vivente che ancora oggi \u00e8 il Santuario Basilica della Consolata a Torino.<\/p>\n<p>Nel volume trovate i seguenti interventi, cos\u00ec organizzati :<\/p>\n<p>Stefano Benedetto: <i>I documenti dell\u2019archivio storico di Torino relativi alla consacrazione della Citt\u00e0 alla Consolata.<\/i><\/p>\n<p>Fabiana Borla: <i>Introduzione alla storia e al patrimonio del Santuario<\/i><\/p>\n<p>Piergiuseppe Menietti: <i>Il 1706\u00a0 e la Consolata<\/i><\/p>\n<p>Ada Quazza: <i>Devozione sabauda alla Consolata.<\/i><\/p>\n<p>Fabiana Borla: La Consolata prima e dopo il 1714<\/p>\n<p>Laura Facchin: <i>L&#8217;iconografia del Valfre&#8217; e la Consolata<\/i><\/p>\n<p>Claudio Brosio: <i>Alcune considerazioni sulle fonti musicali.<\/i><\/p>\n<p>Daniele Bolognini: <i>I santi e la Consolata.<\/i><\/p>\n<p>&nbsp;<\/p>\n<p><b>Immagini<\/b>: 32 pagine di riproduzioni a colori\u00a0 corredare il testo di ca. 150 pagine. 10 \u20ac<\/p>\n<p>Lino Ferracin, curatore<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.laconsolata.org\/wp-content\/uploads\/2014\/05\/copertina-def-web.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-1661\" alt=\"copertina def web\" src=\"http:\/\/www.laconsolata.org\/wp-content\/uploads\/2014\/05\/copertina-def-web.jpg\" width=\"454\" height=\"640\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Catalogo della Mostra &#8220;<strong>300 Anni <strong>Patrona <\/strong>&#8211; la <\/strong>Consolata e la sua citt\u00e0&#8221;<br \/>\n<\/strong><\/p>\n<p>Il volume presenta la catalogazione (foto bianco\/nero e descrizione) dei 166 oggetti, carichi di storia e valore artistico,esposti nella mostra dedicata alle celebrazioni dei Trecento Anni della Consolata Patrona, allestita al Santuario nei locali dell&#8217;ex monastero cistercense e benedettino, ora Convitto Ecclesiastico\u00a0 (aprile-giugno 2014).<\/p>\n<p>La mostra si articola in quattro sezioni:<\/p>\n<p>1) la Proclamazione (21 maggio 1714).<\/p>\n<p>2)\u00a0 L&#8217;ambiente, il tempo, i protagonisti, con l&#8217;accento sull&#8217;apostolo della Consolata, il beato Sebastiano Valfr\u00e9.<\/p>\n<p>3) La diffusione del culto, con pannelli di edicole, rosoni, altari laterali, immaginette e tutto quanto dimostri la diffusione capillare della devozione alla Consolata.<\/p>\n<p>4) i Disegni di 4 scuole torinesi che interpretano e attualizzano la figura della Consolata quale protettrice della citt\u00e0 e dei singoli credenti.<\/p>\n<p>Il testo \u00e8 arricchito da schede di approfondimenti che riguardano la sala dei reliquiari, Sebastiano Valfr\u00e8, Vittorio Amedeo II e gli oggetti di culto (immaginette, medagliette, ecc.).<br \/>\n<b>\u00a0<\/b><\/p>\n<p><b>Immagini<\/b>: 16 pagine di riproduzioni a colori a corredare il testo di 80 pagine.\u00a0 8\u20ac<\/p>\n<p>&nbsp;<\/p>\n<p>Fabiana Borla, curatrice<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;<br \/>\n\u00a0\u00a0<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\nSaggio sui 300 anni della Consolata Patrona di Torino<br \/>\nIl volume si propone di presentare, anzitutto, i\u00a0 momenti essenziali delle circostanze che portarono la Citt\u00e0 di Torino a deliberare la consacrazione della Citt\u00e0 alla Madre di Dio Consolatrice e Consolata (21 Maggio 1714), come segno perenne di ringraziamento dalla temuta distruzione nell\u2019assedio del 1706.<br \/>\nUn altro obiettivo del volume \u00e8 quello di inserire le vicende millenarie del Santuario della Patrona di Torino all\u2019interno della vita militare, civile e religiosa di Torino ed, infine, offrire una guida religiosa, culturale, artistica su quel &#8230;<\/p>\n","protected":false},"author":11,"featured_media":0,"parent":43,"menu_order":6,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"class_list":["post-1659","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.laconsolata.org\/index.php\/wp-json\/wp\/v2\/pages\/1659"}],"collection":[{"href":"https:\/\/www.laconsolata.org\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.laconsolata.org\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.laconsolata.org\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laconsolata.org\/index.php\/wp-json\/wp\/v2\/comments?post=1659"}],"version-history":[{"count":7,"href":"https:\/\/www.laconsolata.org\/index.php\/wp-json\/wp\/v2\/pages\/1659\/revisions"}],"predecessor-version":[{"id":1663,"href":"https:\/\/www.laconsolata.org\/index.php\/wp-json\/wp\/v2\/pages\/1659\/revisions\/1663"}],"up":[{"embeddable":true,"href":"https:\/\/www.laconsolata.org\/index.php\/wp-json\/wp\/v2\/pages\/43"}],"wp:attachment":[{"href":"https:\/\/www.laconsolata.org\/index.php\/wp-json\/wp\/v2\/media?parent=1659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}