{"id":3823,"date":"2018-09-10T13:00:24","date_gmt":"2018-09-10T11:00:24","guid":{"rendered":"http:\/\/www.laconsolata.org\/?p=3823"},"modified":"2026-02-20T15:16:08","modified_gmt":"2026-02-20T14:16:08","slug":"la-nuova-o-n-l-u-s-del-santuario","status":"publish","type":"post","link":"https:\/\/www.laconsolata.org\/index.php\/2018\/09\/10\/la-nuova-o-n-l-u-s-del-santuario\/","title":{"rendered":"La E.T.S. (ex O.N.L.U.S.) del Santuario"},"content":{"rendered":"<h3><strong>Dal 13 novembre 2017 si \u00e8 costituito il Ramo O.N.L.U.S., oggi <span style=\"color: #ff0000;\">Ramo E.T.S.<\/span> del Santuario<\/strong>.<\/h3>\n<p>E&#8217; possibile avere maggiori informazioni consultando la pagina dedicata sul nostro sito internet, oppure contattando il numero telefonico <strong>011\/483.61.10 <\/strong>(ufficio fundraising).<\/p>\n<p>Per donare il <strong>5 x 1000<\/strong> al <strong>Ramo E.T.S.<\/strong> \u00e8 necessario inserire il codice fiscale del Santuario e apporre la vostra firma nella pagina apposita del proprio <strong>modello UNICO <\/strong>o<strong> 730.<\/strong><\/p>\n<p>E&#8217; un&#8217;occasione per sostenere ulteriormente la Consolata, oltre ai metodi diretti di donazione attivi tutto l&#8217;anno previsti per le O.N.L.U.S. ed E.T.S.,\u00a0 <strong><em>operazioni di cui si potr\u00e0 beneficiare delle agevolazioni di legge nella personale denuncia dei redditi<\/em><\/strong><em><strong>.<\/strong><\/em><\/p>\n<p>\u00a0<\/p>\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.laconsolata.org\/wp-content\/uploads\/2018\/09\/5x1000-QUADRATO_2026-scaled.jpg\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"523\" src=\"https:\/\/www.laconsolata.org\/wp-content\/uploads\/2018\/09\/5x1000-QUADRATO_2026-1024x523.jpg\" alt=\"\" class=\"wp-image-5708\" srcset=\"https:\/\/www.laconsolata.org\/wp-content\/uploads\/2018\/09\/5x1000-QUADRATO_2026-1024x523.jpg 1024w, https:\/\/www.laconsolata.org\/wp-content\/uploads\/2018\/09\/5x1000-QUADRATO_2026-300x153.jpg 300w, https:\/\/www.laconsolata.org\/wp-content\/uploads\/2018\/09\/5x1000-QUADRATO_2026-768x392.jpg 768w, https:\/\/www.laconsolata.org\/wp-content\/uploads\/2018\/09\/5x1000-QUADRATO_2026-1536x784.jpg 1536w, https:\/\/www.laconsolata.org\/wp-content\/uploads\/2018\/09\/5x1000-QUADRATO_2026-2048x1045.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Dal 13 novembre 2017 si \u00e8 costituito il Ramo O.N.L.U.S., oggi Ramo E.T.S. del Santuario.<br \/>\nE&#8217; possibile avere maggiori informazioni consultando la pagina dedicata sul nostro sito internet, oppure contattando il numero telefonico 011\/483.61.10 (ufficio fundraising).<br \/>\nPer donare il 5 x 1000 al Ramo E.T.S. \u00e8 necessario inserire il codice fiscale del Santuario e apporre la vostra firma nella pagina apposita del proprio modello UNICO o 730.<br \/>\nE&#8217; un&#8217;occasione per sostenere ulteriormente la Consolata, oltre ai metodi diretti di donazione attivi tutto l&#8217;anno previsti per le O.N.L.U.S. ed E.T.S.,\u00a0 operazioni di cui si &#8230;<\/p>\n","protected":false},"author":11,"featured_media":3819,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-3823","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.laconsolata.org\/index.php\/wp-json\/wp\/v2\/posts\/3823"}],"collection":[{"href":"https:\/\/www.laconsolata.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laconsolata.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laconsolata.org\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laconsolata.org\/index.php\/wp-json\/wp\/v2\/comments?post=3823"}],"version-history":[{"count":24,"href":"https:\/\/www.laconsolata.org\/index.php\/wp-json\/wp\/v2\/posts\/3823\/revisions"}],"predecessor-version":[{"id":5709,"href":"https:\/\/www.laconsolata.org\/index.php\/wp-json\/wp\/v2\/posts\/3823\/revisions\/5709"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laconsolata.org\/index.php\/wp-json\/wp\/v2\/media\/3819"}],"wp:attachment":[{"href":"https:\/\/www.laconsolata.org\/index.php\/wp-json\/wp\/v2\/media?parent=3823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laconsolata.org\/index.php\/wp-json\/wp\/v2\/categories?post=3823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laconsolata.org\/index.php\/wp-json\/wp\/v2\/tags?post=3823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}